{"id":9309,"date":"2010-09-13T22:04:36","date_gmt":"2010-09-13T20:04:36","guid":{"rendered":"http:\/\/www.tribur.de\/blog\/?p=9309"},"modified":"2010-09-13T22:04:36","modified_gmt":"2010-09-13T20:04:36","slug":"archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler","status":"publish","type":"post","link":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/","title":{"rendered":"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler"},"content":{"rendered":"<ul>\n<li>\u00dcber die fr\u00e4nkische K\u00f6nigin Radegunde, die Nonne wurde und ihren Ruhm als K\u00f6chin schreibt der <a href=\"http:\/\/www.suedkurier.de\/region\/kreis-konstanz\/gaienhofen\/Radegundes-Fleischragout-als-Hauptnahrungsmittel-im-Mittelalter;art372440,4474074\" target=\"_blank\">S\u00fcdkurier<\/a><\/li>\n<li>\u00dcber den Tag des offenen Denkmals in Euerdorf schreibt die <a href=\"http:\/\/www.mainpost.de\/lokales\/bad-kissingen\/Euerdorf-als-ein-begehbares-Geschichtsbuch;art770,5726593\" target=\"_blank\">Main Post<\/a><\/li>\n<li>Auch in Ingelheim gabs zum Tag des offenen Denkmals Aktionen und hier schreibt die <a href=\"http:\/\/www.allgemeine-zeitung.de\/region\/ingelheim\/ingelheim\/9389378.htm\" target=\"_blank\">Allgemeine Zeitung<\/a> dar\u00fcber<\/li>\n<li>\u00dcber Wikipedia und Geschichtswissenschaften schreibt die <a href=\"http:\/\/www.nzz.ch\/nachrichten\/startseite\/per_mausklick_zur_schlacht_am_morgarten_1.7536473.html\" target=\"_blank\">NZZ<\/a><\/li>\n<li>Die <a href=\"http:\/\/www.mainpost.de\/nachrichten\/kulturwelt\/dpakultur\/Mutmassliche-Grabstaette-von-Zar-Iwan-VI-entdeckt;art584,5726468\" target=\"_blank\">Main Post<\/a> schreibt auch \u00fcber die m\u00f6gliche Entdeckung des Grabes von Zar Iwan VI. (1740-64) der 23 Jahre seines Lebens in Haft verbrachte<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber die fr\u00e4nkische K\u00f6nigin Radegunde, die Nonne wurde und ihren Ruhm als K\u00f6chin schreibt der S\u00fcdkurier \u00dcber den Tag des offenen Denkmals in Euerdorf schreibt die Main Post Auch in Ingelheim gabs zum Tag&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,56],"tags":[],"class_list":["post-9309","post","type-post","status-publish","format-standard","hentry","category-geschichte","category-links"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler - Tribur.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler - Tribur.de\" \/>\n<meta property=\"og:description\" content=\"\u00dcber die fr\u00e4nkische K\u00f6nigin Radegunde, die Nonne wurde und ihren Ruhm als K\u00f6chin schreibt der S\u00fcdkurier \u00dcber den Tag des offenen Denkmals in Euerdorf schreibt die Main Post Auch in Ingelheim gabs zum Tag&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/\" \/>\n<meta property=\"og:site_name\" content=\"Tribur.de\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-13T20:04:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-2.jpg?fit=200%2C200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Markus Zwittmeier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/tribur\" \/>\n<meta name=\"twitter:site\" content=\"@tribur\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Markus Zwittmeier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/\"},\"author\":{\"name\":\"Markus Zwittmeier\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"headline\":\"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler\",\"datePublished\":\"2010-09-13T20:04:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/\"},\"wordCount\":91,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"articleSection\":[\"Geschichte\",\"Links\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/\",\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/\",\"name\":\"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler - Tribur.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#website\"},\"datePublished\":\"2010-09-13T20:04:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/09\\\/13\\\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/\",\"name\":\"Tribur.de\",\"description\":\"Tribur.de - Geschichte und so Zeugs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\",\"name\":\"Markus Zwittmeier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"width\":200,\"height\":200,\"caption\":\"Markus Zwittmeier\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.Tribur.de\",\"http:\\\/\\\/www.facebook.com\\\/pages\\\/Triburde\\\/184352328288771\",\"https:\\\/\\\/www.instagram.com\\\/tribur.de\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/tribur\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCnEonou-x6_P4XPjBk2htCA\"],\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/author\\\/markus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler - Tribur.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/","og_locale":"de_DE","og_type":"article","og_title":"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler - Tribur.de","og_description":"\u00dcber die fr\u00e4nkische K\u00f6nigin Radegunde, die Nonne wurde und ihren Ruhm als K\u00f6chin schreibt der S\u00fcdkurier \u00dcber den Tag des offenen Denkmals in Euerdorf schreibt die Main Post Auch in Ingelheim gabs zum Tag&#46;&#46;&#46;","og_url":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/","og_site_name":"Tribur.de","article_publisher":"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","article_author":"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","article_published_time":"2010-09-13T20:04:36+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-2.jpg?fit=200%2C200&ssl=1","type":"image\/jpeg"}],"author":"Markus Zwittmeier","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/tribur","twitter_site":"@tribur","twitter_misc":{"Verfasst von":"Markus Zwittmeier"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/#article","isPartOf":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/"},"author":{"name":"Markus Zwittmeier","@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"headline":"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler","datePublished":"2010-09-13T20:04:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/"},"wordCount":91,"commentCount":0,"publisher":{"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"articleSection":["Geschichte","Links"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/","url":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/","name":"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler - Tribur.de","isPartOf":{"@id":"https:\/\/www.tribur.de\/blog\/#website"},"datePublished":"2010-09-13T20:04:36+00:00","breadcrumb":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tribur.de\/blog\/2010\/09\/13\/archaonews-13-09-2010-radegunde-zar-iwan-iv-und-offene-denkmaler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tribur.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Arch\u00e4onews 13.09.2010 Radegunde, Zar Iwan IV und offene Denkm\u00e4ler"}]},{"@type":"WebSite","@id":"https:\/\/www.tribur.de\/blog\/#website","url":"https:\/\/www.tribur.de\/blog\/","name":"Tribur.de","description":"Tribur.de - Geschichte und so Zeugs","publisher":{"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tribur.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c","name":"Markus Zwittmeier","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","url":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","width":200,"height":200,"caption":"Markus Zwittmeier"},"logo":{"@id":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1"},"sameAs":["http:\/\/www.Tribur.de","http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","https:\/\/www.instagram.com\/tribur.de\/","https:\/\/x.com\/https:\/\/twitter.com\/tribur","https:\/\/www.youtube.com\/channel\/UCnEonou-x6_P4XPjBk2htCA"],"url":"https:\/\/www.tribur.de\/blog\/author\/markus\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p1mHPu-2q9","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/9309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/comments?post=9309"}],"version-history":[{"count":6,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/9309\/revisions"}],"predecessor-version":[{"id":9315,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/9309\/revisions\/9315"}],"wp:attachment":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/media?parent=9309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/categories?post=9309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/tags?post=9309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}