{"id":7960,"date":"2010-07-26T14:16:59","date_gmt":"2010-07-26T12:16:59","guid":{"rendered":"http:\/\/www.tribur.de\/blog\/?p=7960"},"modified":"2010-07-26T16:10:33","modified_gmt":"2010-07-26T14:10:33","slug":"agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2","status":"publish","type":"post","link":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/","title":{"rendered":"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive"},"content":{"rendered":"<p>&#8222;Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive&#8220; ist der etwas sperrige Titel eines PDFs das ich gefunden habe. Es stammt aus dem historischen Seminar der Universit\u00e4t Z\u00fcrich, genauer gesagt von Frau Dr. Dorothee Rippmann, Privatdozentin f\u00fcr Geschichte des Mittelalters und Gastprofessorin am Institut f\u00fcr Geschichte der Universit\u00e4t Wien 2009\/2010.<br \/>\nDrauf gesto\u00dfen bin ich wegen erg\u00e4nzender Informationen zum Brevium Exempla, das sie am Anfang des Textes behandelt. Leider scheint ihre \u00dcbersetzung des Brevium Exempla ein wenig mit der meinigen zu kolidiert, was vielleicht daran liegt, das ich eine andere (Dopsch), sowie eine Englische Version benutze \ud83d\ude09<br \/>\nDennoch gibt sie in ihrem Text eine interessanten Blick auf die Arbeitswelt der Frau im Mittelalter frei.<\/p>\n<p><a href=\"http:\/\/www.hist.uzh.ch\/lehre\/mittelalter\/rippmann\/forschung\/newsletterAKA-Bilder.pdf\" target=\"_blank\">Hier findet sich das PDF<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive&#8220; ist der etwas sperrige Titel eines PDFs das ich gefunden habe. Es stammt aus dem historischen Seminar der Universit\u00e4t Z\u00fcrich, genauer gesagt von Frau Dr. Dorothee Rippmann, Privatdozentin&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[11,32,35,49],"class_list":["post-7960","post","type-post","status-publish","format-standard","hentry","category-geschichte","tag-fruhmittelalter","tag-karolingisch","tag-pfalz","tag-recherche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive - Tribur.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive - Tribur.de\" \/>\n<meta property=\"og:description\" content=\"&#8222;Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive&#8220; ist der etwas sperrige Titel eines PDFs das ich gefunden habe. Es stammt aus dem historischen Seminar der Universit\u00e4t Z\u00fcrich, genauer gesagt von Frau Dr. Dorothee Rippmann, Privatdozentin&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tribur.de\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-26T12:16:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-07-26T14:10:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-2.jpg?fit=200%2C200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Markus Zwittmeier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/tribur\" \/>\n<meta name=\"twitter:site\" content=\"@tribur\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Markus Zwittmeier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/\"},\"author\":{\"name\":\"Markus Zwittmeier\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"headline\":\"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive\",\"datePublished\":\"2010-07-26T12:16:59+00:00\",\"dateModified\":\"2010-07-26T14:10:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/\"},\"wordCount\":128,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"keywords\":[\"Fr\u00fchmittelalter\",\"karolingisch\",\"Pfalz\",\"Recherche\"],\"articleSection\":[\"Geschichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/\",\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/\",\"name\":\"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive - Tribur.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#website\"},\"datePublished\":\"2010-07-26T12:16:59+00:00\",\"dateModified\":\"2010-07-26T14:10:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/26\\\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/\",\"name\":\"Tribur.de\",\"description\":\"Tribur.de - Geschichte und so Zeugs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\",\"name\":\"Markus Zwittmeier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"width\":200,\"height\":200,\"caption\":\"Markus Zwittmeier\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.Tribur.de\",\"http:\\\/\\\/www.facebook.com\\\/pages\\\/Triburde\\\/184352328288771\",\"https:\\\/\\\/www.instagram.com\\\/tribur.de\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/tribur\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCnEonou-x6_P4XPjBk2htCA\"],\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/author\\\/markus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive - Tribur.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/","og_locale":"de_DE","og_type":"article","og_title":"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive - Tribur.de","og_description":"&#8222;Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive&#8220; ist der etwas sperrige Titel eines PDFs das ich gefunden habe. Es stammt aus dem historischen Seminar der Universit\u00e4t Z\u00fcrich, genauer gesagt von Frau Dr. Dorothee Rippmann, Privatdozentin&#46;&#46;&#46;","og_url":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/","og_site_name":"Tribur.de","article_publisher":"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","article_author":"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","article_published_time":"2010-07-26T12:16:59+00:00","article_modified_time":"2010-07-26T14:10:33+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-2.jpg?fit=200%2C200&ssl=1","type":"image\/jpeg"}],"author":"Markus Zwittmeier","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/tribur","twitter_site":"@tribur","twitter_misc":{"Verfasst von":"Markus Zwittmeier","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/#article","isPartOf":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/"},"author":{"name":"Markus Zwittmeier","@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"headline":"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive","datePublished":"2010-07-26T12:16:59+00:00","dateModified":"2010-07-26T14:10:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/"},"wordCount":128,"commentCount":1,"publisher":{"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"keywords":["Fr\u00fchmittelalter","karolingisch","Pfalz","Recherche"],"articleSection":["Geschichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/","url":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/","name":"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive - Tribur.de","isPartOf":{"@id":"https:\/\/www.tribur.de\/blog\/#website"},"datePublished":"2010-07-26T12:16:59+00:00","dateModified":"2010-07-26T14:10:33+00:00","breadcrumb":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/26\/agrargeschichte-des-mittelalters-aus-geschlechtergeschichtlicher-perspektive-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tribur.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Agrargeschichte des Mittelalters aus geschlechtergeschichtlicher Perspektive"}]},{"@type":"WebSite","@id":"https:\/\/www.tribur.de\/blog\/#website","url":"https:\/\/www.tribur.de\/blog\/","name":"Tribur.de","description":"Tribur.de - Geschichte und so Zeugs","publisher":{"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tribur.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c","name":"Markus Zwittmeier","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","url":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","width":200,"height":200,"caption":"Markus Zwittmeier"},"logo":{"@id":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1"},"sameAs":["http:\/\/www.Tribur.de","http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","https:\/\/www.instagram.com\/tribur.de\/","https:\/\/x.com\/https:\/\/twitter.com\/tribur","https:\/\/www.youtube.com\/channel\/UCnEonou-x6_P4XPjBk2htCA"],"url":"https:\/\/www.tribur.de\/blog\/author\/markus\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p1mHPu-24o","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/7960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/comments?post=7960"}],"version-history":[{"count":4,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/7960\/revisions"}],"predecessor-version":[{"id":7971,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/7960\/revisions\/7971"}],"wp:attachment":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/media?parent=7960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/categories?post=7960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/tags?post=7960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}