{"id":7680,"date":"2010-07-12T14:06:23","date_gmt":"2010-07-12T12:06:23","guid":{"rendered":"http:\/\/www.tribur.de\/blog\/?p=7680"},"modified":"2010-07-12T14:06:23","modified_gmt":"2010-07-12T12:06:23","slug":"die-mauerreste-der-pfalz-sollen-sichtbar-bleiben","status":"publish","type":"post","link":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/","title":{"rendered":"Die Mauerreste der Pfalz sollen sichtbar bleiben"},"content":{"rendered":"<p>In Kaiserslautern wurden bei Grabungen Mauerreste der einstigen Pfalz freigelegt. Urspr\u00fcnglich waren nur punktuelle Sondagen geplant, aber Probegrabungen waren so erfolgreich das man nun weitere Grabungen durchf\u00fchrt.<br \/>\nDie Erkenntnisse sind wohl so weitreichend , das Grabungen aus den 30er Jahren revidiert werden m\u00fcssen.<br \/>\nDer Oberb\u00fcrgermeister scheint so auch viel vorgenommen zu haben, denn man m\u00f6chte die gefundenen mauerz\u00fcge am liebsten gleich f\u00fcr alle Sichtbar machen:<\/p>\n<blockquote>\n<p>Der vom Stadtrat 2009 genehmigte Rahmenplan zur Umgestaltung und \u00dcberplanung des Burgberges sieht diese Ma\u00dfnahme erst zu einem sp\u00e4teren Zeitpunkt vor. \u201eEs macht aber keinen Sinn, jetzt wieder alles zuzusch\u00fctten und erst in f\u00fcnf Jahren an dieser Stelle wieder zu beginnen\u201c, so Oberb\u00fcrgermeister Dr. Klaus Weichel. \u201eIch werde mich jetzt aus den genannten Gr\u00fcnden daf\u00fcr stark machen, die endg\u00fcltige Ma\u00dfnahme vorzuziehen. Konkret bedeutet dies, dass ich dem Stadtrat in der ersten Sitzung nach der Sommerpause vorschlagen werde, die Mittel bereitzustellen, damit wir noch 2011 anfangen k\u00f6nnen, die geschichtlichen Zeitzeugnisse an dieser Stelle aufzuarbeiten.\u201c<\/p>\n<\/blockquote>\n<p><a href=\"http:\/\/www.prport.net\/die-ausgrabungen-bleiben-offen-pr71791.html\" target=\"_blank\">Hier die Pressemeldung<\/a> und hier <a href=\"http:\/\/www.kaiserpfalz-kaiserslautern.de\/index.html\" target=\"_blank\">die Seite des F\u00f6rderkreis zur Erhaltung der Pfalz<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Kaiserslautern wurden bei Grabungen Mauerreste der einstigen Pfalz freigelegt. Urspr\u00fcnglich waren nur punktuelle Sondagen geplant, aber Probegrabungen waren so erfolgreich das man nun weitere Grabungen durchf\u00fchrt. Die Erkenntnisse sind wohl so weitreichend ,&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[54,12,35,60],"class_list":["post-7680","post","type-post","status-publish","format-standard","hentry","category-geschichte","tag-archaologie","tag-hochmittelalter","tag-pfalz","tag-staufisch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Mauerreste der Pfalz sollen sichtbar bleiben - Tribur.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Mauerreste der Pfalz sollen sichtbar bleiben - Tribur.de\" \/>\n<meta property=\"og:description\" content=\"In Kaiserslautern wurden bei Grabungen Mauerreste der einstigen Pfalz freigelegt. Urspr\u00fcnglich waren nur punktuelle Sondagen geplant, aber Probegrabungen waren so erfolgreich das man nun weitere Grabungen durchf\u00fchrt. Die Erkenntnisse sind wohl so weitreichend ,&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/\" \/>\n<meta property=\"og:site_name\" content=\"Tribur.de\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-12T12:06:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-2.jpg?fit=200%2C200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Markus Zwittmeier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/tribur\" \/>\n<meta name=\"twitter:site\" content=\"@tribur\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Markus Zwittmeier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/\"},\"author\":{\"name\":\"Markus Zwittmeier\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"headline\":\"Die Mauerreste der Pfalz sollen sichtbar bleiben\",\"datePublished\":\"2010-07-12T12:06:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/\"},\"wordCount\":193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"keywords\":[\"Arch\u00e4ologie\",\"Hochmittelalter\",\"Pfalz\",\"staufisch\"],\"articleSection\":[\"Geschichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/\",\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/\",\"name\":\"Die Mauerreste der Pfalz sollen sichtbar bleiben - Tribur.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#website\"},\"datePublished\":\"2010-07-12T12:06:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2010\\\/07\\\/12\\\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Mauerreste der Pfalz sollen sichtbar bleiben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/\",\"name\":\"Tribur.de\",\"description\":\"Tribur.de - Geschichte und so Zeugs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\",\"name\":\"Markus Zwittmeier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"width\":200,\"height\":200,\"caption\":\"Markus Zwittmeier\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.Tribur.de\",\"http:\\\/\\\/www.facebook.com\\\/pages\\\/Triburde\\\/184352328288771\",\"https:\\\/\\\/www.instagram.com\\\/tribur.de\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/tribur\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCnEonou-x6_P4XPjBk2htCA\"],\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/author\\\/markus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Mauerreste der Pfalz sollen sichtbar bleiben - Tribur.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/","og_locale":"de_DE","og_type":"article","og_title":"Die Mauerreste der Pfalz sollen sichtbar bleiben - Tribur.de","og_description":"In Kaiserslautern wurden bei Grabungen Mauerreste der einstigen Pfalz freigelegt. Urspr\u00fcnglich waren nur punktuelle Sondagen geplant, aber Probegrabungen waren so erfolgreich das man nun weitere Grabungen durchf\u00fchrt. Die Erkenntnisse sind wohl so weitreichend ,&#46;&#46;&#46;","og_url":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/","og_site_name":"Tribur.de","article_publisher":"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","article_author":"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","article_published_time":"2010-07-12T12:06:23+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-2.jpg?fit=200%2C200&ssl=1","type":"image\/jpeg"}],"author":"Markus Zwittmeier","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/tribur","twitter_site":"@tribur","twitter_misc":{"Verfasst von":"Markus Zwittmeier","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/#article","isPartOf":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/"},"author":{"name":"Markus Zwittmeier","@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"headline":"Die Mauerreste der Pfalz sollen sichtbar bleiben","datePublished":"2010-07-12T12:06:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/"},"wordCount":193,"commentCount":0,"publisher":{"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"keywords":["Arch\u00e4ologie","Hochmittelalter","Pfalz","staufisch"],"articleSection":["Geschichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/","url":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/","name":"Die Mauerreste der Pfalz sollen sichtbar bleiben - Tribur.de","isPartOf":{"@id":"https:\/\/www.tribur.de\/blog\/#website"},"datePublished":"2010-07-12T12:06:23+00:00","breadcrumb":{"@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tribur.de\/blog\/2010\/07\/12\/die-mauerreste-der-pfalz-sollen-sichtbar-bleiben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tribur.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Die Mauerreste der Pfalz sollen sichtbar bleiben"}]},{"@type":"WebSite","@id":"https:\/\/www.tribur.de\/blog\/#website","url":"https:\/\/www.tribur.de\/blog\/","name":"Tribur.de","description":"Tribur.de - Geschichte und so Zeugs","publisher":{"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tribur.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c","name":"Markus Zwittmeier","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","url":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","width":200,"height":200,"caption":"Markus Zwittmeier"},"logo":{"@id":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1"},"sameAs":["http:\/\/www.Tribur.de","http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","https:\/\/www.instagram.com\/tribur.de\/","https:\/\/x.com\/https:\/\/twitter.com\/tribur","https:\/\/www.youtube.com\/channel\/UCnEonou-x6_P4XPjBk2htCA"],"url":"https:\/\/www.tribur.de\/blog\/author\/markus\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p1mHPu-1ZS","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/7680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/comments?post=7680"}],"version-history":[{"count":2,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/7680\/revisions"}],"predecessor-version":[{"id":7687,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/7680\/revisions\/7687"}],"wp:attachment":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/media?parent=7680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/categories?post=7680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/tags?post=7680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}