{"id":684,"date":"2009-04-04T20:41:46","date_gmt":"2009-04-04T19:41:46","guid":{"rendered":"http:\/\/www.tribur.de\/blog\/?p=684"},"modified":"2009-04-04T20:45:02","modified_gmt":"2009-04-04T19:45:02","slug":"zu-historischen-statten-durch-fluren-und-gewanne","status":"publish","type":"post","link":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/","title":{"rendered":"&#8230;zu historischen St\u00e4tten durch Fluren und Gewanne&#8230;"},"content":{"rendered":"<p>&#8222;Wanderung zu historischen St\u00e4tten und Gewannen\u00a0 in der Gemarkung Trebur&#8220; unter diesem Motto habe ich meinen Nachmittag verbacht. Die Wanderung wurde vom Treburer Geschichtsverein unter Herrn Kraft durchgef\u00fchrt, f\u00fchrte von Trebur nach Norden \u00fcber den alten Bauschheimer Weg. Weiter nach Norden, vorbei am <a href=\"http:\/\/www.jungsteinsite.uni-kiel.de\/2002_mueller\/c14_trebur.htm\" target=\"_self\">Fundplatz Tannb\u00f6hl<\/a>, einem der wichtigsten neolithischen Fundst\u00e4tten Europas, zum letzter Treburer Zollstein, der in Zukunft restauriert werden soll.<\/p>\n<p>Nebenbei hab mein erstes Interview dem Darmst\u00e4dter Echo gegeben \ud83d\ude09 und wehe Ihr schreibt meinen Namen falsch!<\/p>\n<p>Hier ein paar Bilder<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3372\/3411750539_de4e13572c.jpg?resize=500%2C375\" alt=\"\" width=\"500\" height=\"375\" \/>Kurze Erl\u00e4uterung an einer Laache, einem ehemaligen Main-Arm, der heute trocken liegt, fr\u00fcher aber bei starken Eis des Mains bei Fl\u00f6rsheim oder starkem Hochwasser wurde das Wasser durch die lockeren Erdschichten der Altarme in den Armen wieder hochgedr\u00fcckt.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3355\/3412557166_d012a78382.jpg?resize=375%2C500\" alt=\"\" width=\"375\" height=\"500\" \/>Herr Kraft erl\u00e4utert den letzten Treburer Zollstein, die anderen rund um Trebur sind mit der Zeit\u00a0 unter recht dubiosen Umst\u00e4nden verloren gegeangen.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3635\/3411752193_e0330f9e64.jpg?resize=500%2C375\" alt=\"\" width=\"500\" height=\"375\" \/>Eine alte Karte der n\u00f6rdlichen Gemarkungen Treburs. Gelb markiert sind die alten Stra\u00dfen die ehemals Sternf\u00f6rmig in den Pfalzort liefen. Der Nachmittag wurde bei Handk\u00e4s und noch sehr intressanten Gespr\u00e4chen, auch die Zukunft betreffend, ausklingen lassen.<\/p>\n<p>Ach h\u00f6rt sich das alles spie\u00dfig an&#8230; \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Wanderung zu historischen St\u00e4tten und Gewannen\u00a0 in der Gemarkung Trebur&#8220; unter diesem Motto habe ich meinen Nachmittag verbacht. Die Wanderung wurde vom Treburer Geschichtsverein unter Herrn Kraft durchgef\u00fchrt, f\u00fchrte von Trebur nach Norden \u00fcber&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[16],"class_list":["post-684","post","type-post","status-publish","format-standard","hentry","category-geschichte","tag-trebur"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>...zu historischen St\u00e4tten durch Fluren und Gewanne... - Tribur.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"...zu historischen St\u00e4tten durch Fluren und Gewanne... - Tribur.de\" \/>\n<meta property=\"og:description\" content=\"&#8222;Wanderung zu historischen St\u00e4tten und Gewannen\u00a0 in der Gemarkung Trebur&#8220; unter diesem Motto habe ich meinen Nachmittag verbacht. Die Wanderung wurde vom Treburer Geschichtsverein unter Herrn Kraft durchgef\u00fchrt, f\u00fchrte von Trebur nach Norden \u00fcber&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/\" \/>\n<meta property=\"og:site_name\" content=\"Tribur.de\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-04T19:41:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-04-04T19:45:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/farm4.static.flickr.com\/3372\/3411750539_de4e13572c.jpg?v=0\" \/>\n<meta name=\"author\" content=\"Markus Zwittmeier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/tribur\" \/>\n<meta name=\"twitter:site\" content=\"@tribur\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Markus Zwittmeier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/\"},\"author\":{\"name\":\"Markus Zwittmeier\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"headline\":\"&#8230;zu historischen St\u00e4tten durch Fluren und Gewanne&#8230;\",\"datePublished\":\"2009-04-04T19:41:46+00:00\",\"dateModified\":\"2009-04-04T19:45:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/\"},\"wordCount\":213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/farm4.static.flickr.com\\\/3372\\\/3411750539_de4e13572c.jpg?v=0\",\"keywords\":[\"Trebur\\\/Tribur\"],\"articleSection\":[\"Geschichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/\",\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/\",\"name\":\"...zu historischen St\u00e4tten durch Fluren und Gewanne... - Tribur.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/farm4.static.flickr.com\\\/3372\\\/3411750539_de4e13572c.jpg?v=0\",\"datePublished\":\"2009-04-04T19:41:46+00:00\",\"dateModified\":\"2009-04-04T19:45:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/#primaryimage\",\"url\":\"http:\\\/\\\/farm4.static.flickr.com\\\/3372\\\/3411750539_de4e13572c.jpg?v=0\",\"contentUrl\":\"http:\\\/\\\/farm4.static.flickr.com\\\/3372\\\/3411750539_de4e13572c.jpg?v=0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/2009\\\/04\\\/04\\\/zu-historischen-statten-durch-fluren-und-gewanne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8230;zu historischen St\u00e4tten durch Fluren und Gewanne&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/\",\"name\":\"Tribur.de\",\"description\":\"Tribur.de - Geschichte und so Zeugs\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/#\\\/schema\\\/person\\\/3119997f09f43791809c2d1af27bba6c\",\"name\":\"Markus Zwittmeier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\",\"width\":200,\"height\":200,\"caption\":\"Markus Zwittmeier\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.tribur.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.Tribur.de\",\"http:\\\/\\\/www.facebook.com\\\/pages\\\/Triburde\\\/184352328288771\",\"https:\\\/\\\/www.instagram.com\\\/tribur.de\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/tribur\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCnEonou-x6_P4XPjBk2htCA\"],\"url\":\"https:\\\/\\\/www.tribur.de\\\/blog\\\/author\\\/markus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"...zu historischen St\u00e4tten durch Fluren und Gewanne... - Tribur.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/","og_locale":"de_DE","og_type":"article","og_title":"...zu historischen St\u00e4tten durch Fluren und Gewanne... - Tribur.de","og_description":"&#8222;Wanderung zu historischen St\u00e4tten und Gewannen\u00a0 in der Gemarkung Trebur&#8220; unter diesem Motto habe ich meinen Nachmittag verbacht. Die Wanderung wurde vom Treburer Geschichtsverein unter Herrn Kraft durchgef\u00fchrt, f\u00fchrte von Trebur nach Norden \u00fcber&#46;&#46;&#46;","og_url":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/","og_site_name":"Tribur.de","article_publisher":"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","article_author":"http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","article_published_time":"2009-04-04T19:41:46+00:00","article_modified_time":"2009-04-04T19:45:02+00:00","og_image":[{"url":"http:\/\/farm4.static.flickr.com\/3372\/3411750539_de4e13572c.jpg?v=0","type":"","width":"","height":""}],"author":"Markus Zwittmeier","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/tribur","twitter_site":"@tribur","twitter_misc":{"Verfasst von":"Markus Zwittmeier","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/#article","isPartOf":{"@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/"},"author":{"name":"Markus Zwittmeier","@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"headline":"&#8230;zu historischen St\u00e4tten durch Fluren und Gewanne&#8230;","datePublished":"2009-04-04T19:41:46+00:00","dateModified":"2009-04-04T19:45:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/"},"wordCount":213,"commentCount":0,"publisher":{"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"image":{"@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/#primaryimage"},"thumbnailUrl":"http:\/\/farm4.static.flickr.com\/3372\/3411750539_de4e13572c.jpg?v=0","keywords":["Trebur\/Tribur"],"articleSection":["Geschichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/","url":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/","name":"...zu historischen St\u00e4tten durch Fluren und Gewanne... - Tribur.de","isPartOf":{"@id":"https:\/\/www.tribur.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/#primaryimage"},"image":{"@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/#primaryimage"},"thumbnailUrl":"http:\/\/farm4.static.flickr.com\/3372\/3411750539_de4e13572c.jpg?v=0","datePublished":"2009-04-04T19:41:46+00:00","dateModified":"2009-04-04T19:45:02+00:00","breadcrumb":{"@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/#primaryimage","url":"http:\/\/farm4.static.flickr.com\/3372\/3411750539_de4e13572c.jpg?v=0","contentUrl":"http:\/\/farm4.static.flickr.com\/3372\/3411750539_de4e13572c.jpg?v=0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tribur.de\/blog\/2009\/04\/04\/zu-historischen-statten-durch-fluren-und-gewanne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tribur.de\/blog\/"},{"@type":"ListItem","position":2,"name":"&#8230;zu historischen St\u00e4tten durch Fluren und Gewanne&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.tribur.de\/blog\/#website","url":"https:\/\/www.tribur.de\/blog\/","name":"Tribur.de","description":"Tribur.de - Geschichte und so Zeugs","publisher":{"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tribur.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.tribur.de\/blog\/#\/schema\/person\/3119997f09f43791809c2d1af27bba6c","name":"Markus Zwittmeier","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","url":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1","width":200,"height":200,"caption":"Markus Zwittmeier"},"logo":{"@id":"https:\/\/i0.wp.com\/www.tribur.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-logotest-4.jpg?fit=200%2C200&ssl=1"},"sameAs":["http:\/\/www.Tribur.de","http:\/\/www.facebook.com\/pages\/Triburde\/184352328288771","https:\/\/www.instagram.com\/tribur.de\/","https:\/\/x.com\/https:\/\/twitter.com\/tribur","https:\/\/www.youtube.com\/channel\/UCnEonou-x6_P4XPjBk2htCA"],"url":"https:\/\/www.tribur.de\/blog\/author\/markus\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1mHPu-b2","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/comments?post=684"}],"version-history":[{"count":3,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/684\/revisions"}],"predecessor-version":[{"id":686,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/posts\/684\/revisions\/686"}],"wp:attachment":[{"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/media?parent=684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/categories?post=684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tribur.de\/blog\/wp-json\/wp\/v2\/tags?post=684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}